{"id":145094,"date":"2017-06-15T09:51:38","date_gmt":"2017-06-15T09:51:38","guid":{"rendered":"http:\/\/ecolecaritas.be\/new\/?p=145094"},"modified":"2017-06-15T09:51:38","modified_gmt":"2017-06-15T09:51:38","slug":"les-repetitions","status":"publish","type":"post","link":"https:\/\/ecolecaritas.be\/new\/les-repetitions\/","title":{"rendered":"Les r\u00e9p\u00e9titions"},"content":{"rendered":"<p>Les r\u00e9p\u00e9titions vont bons train pour pr\u00e9parer la f\u00eate de l&rsquo;\u00e9cole !<\/p>\n<p>Dans la bonne humeur et sous le soleil, tout le monde est impatient !<\/p>\n<div class=\"rl-gallery-container \" id=\"rl-gallery-container-1\" data-gallery_id=\"0\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-1\" data-gallery_no=\"1\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/130.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/130-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/128.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/128-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/126.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/126-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/121.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/121-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/117.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/117-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/116.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/116-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/115.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/115-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/113.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/113-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/112.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/112-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/110.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/110-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/107.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/107-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/106.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/106-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/104.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/104-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/103.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/103-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/100.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/100-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/099.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/099-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/096.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/096-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/090.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/090-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/079.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/079-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/074.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/074-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/071.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/071-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/069.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/069-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/068.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/068-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/062.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/062-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/060.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/060-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/058.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/058-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/056.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/056-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/053.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/053-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/052.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/052-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/050.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/050-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/049.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/049-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/048.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/048-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/045.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/045-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/043.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/043-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/042.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/042-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/039.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/039-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/038.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/038-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/036.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/036-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/035.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/035-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/034.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/034-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/033.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/033-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/030.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/030-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/027.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/027-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/026.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecolecaritas.be\/new\/wp-content\/uploads\/2017\/06\/026-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" \/><\/a><\/div> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Les r\u00e9p\u00e9titions vont bons train pour pr\u00e9parer la f\u00eate de l&rsquo;\u00e9cole ! Dans la bonne humeur et sous le soleil, tout le monde est impatient <a class=\"mh-excerpt-more\" href=\"https:\/\/ecolecaritas.be\/new\/les-repetitions\/\" title=\"Les r\u00e9p\u00e9titions\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":5,"featured_media":145183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-145094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/posts\/145094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/comments?post=145094"}],"version-history":[{"count":3,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/posts\/145094\/revisions"}],"predecessor-version":[{"id":145246,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/posts\/145094\/revisions\/145246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/media\/145183"}],"wp:attachment":[{"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/media?parent=145094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/categories?post=145094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolecaritas.be\/new\/wp-json\/wp\/v2\/tags?post=145094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}